{"id":10055,"date":"2024-09-27T15:05:57","date_gmt":"2024-09-27T07:05:57","guid":{"rendered":"https:\/\/appnicorn.com\/?page_id=10055"},"modified":"2025-02-17T17:14:31","modified_gmt":"2025-02-17T09:14:31","slug":"our-work","status":"publish","type":"page","link":"https:\/\/appnicorn.com\/zh\/our-work\/","title":{"rendered":"\u5ba2\u6237\u6848\u4f8b"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"10055\" class=\"elementor elementor-10055\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8757692 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8757692\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95f8959\" data-id=\"95f8959\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-359ff21 elementor-widget elementor-widget-heading\" data-id=\"359ff21\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 09-08-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">\u5ba2\u6237\u6848\u4f8b<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e231a79 elementor-widget elementor-widget-heading\" data-id=\"e231a79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u4e3a\u54c1\u724c\u8bbe\u8ba1\u5177\u6709\u5f71\u54cd\u529b\u7684\u5728\u7ebf\u5f62\u8c61\u3002<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d27333d elementor-widget elementor-widget-text-editor\" data-id=\"d27333d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 09-08-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Appnicorn\u662f\u4e00\u5bb6\u5145\u6ee1\u6d3b\u529b\u7684\u7f51\u7ad9\u642d\u5efa\u516c\u53f8\uff0c \u64c5\u957f\u901a\u8fc7\u7f51\u9875\u8bbe\u8ba1\u3001 \u6218\u7565SEO\u3001 \u7535\u5b50\u5546\u52a1\u89e3\u51b3\u65b9\u6848\u548c\u5e94\u7528\u5f00\u53d1\uff0c \u5c06\u60a8\u7684\u54c1\u724c\u613f\u666f\u53d8\u4e3a\u73b0\u5b9e\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9ee2eeb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ee2eeb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9ba08ce\" data-id=\"9ba08ce\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fba79c elementor-widget elementor-widget-heading\" data-id=\"2fba79c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Simble<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff16efd elementor-widget elementor-widget-text-editor\" data-id=\"ff16efd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7b80\u6d01\u4e14\u7528\u6237\u53cb\u597d\u7684WordPress\u7f51\u7ad9\uff0c \u652f\u6301\u7535\u5b50\u5546\u52a1\u529f\u80fd\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8c500 elementor-widget elementor-widget-text-editor\" data-id=\"ee8c500\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1 | \u7535\u5b50\u5546\u52a1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c2c2b5 elementor-widget elementor-widget-premium-image-scroll\" data-id=\"1c2c2b5\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/simble\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1759\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife.jpg\" class=\"attachment-full size-full wp-image-10230\" alt=\"Appnicorn Work - Simble\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife-162x300.jpg 162w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife-553x1024.jpg 553w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife-768x1422.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife-830x1536.jpg 830w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife-6x12.jpg 6w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife-600x1111.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-954c081\" data-id=\"954c081\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11ba64b elementor-widget elementor-widget-heading\" data-id=\"11ba64b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">iGOZO<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90ded3d elementor-widget elementor-widget-text-editor\" data-id=\"90ded3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u9ad8\u54c1\u8d28\u708a\u5177\u7684\u4e00\u7ad9\u5f0f\u5728\u7ebf\u5546\u5e97\uff0c \u63d0\u5347\u987e\u5ba2\u7684\u70f9\u996a\u4f53\u9a8c\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-480908e elementor-widget elementor-widget-text-editor\" data-id=\"480908e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1 | \u7535\u5b50\u5546\u52a1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60a310f elementor-widget elementor-widget-premium-image-scroll\" data-id=\"60a310f\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/igozo\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"2174\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo.jpg\" class=\"attachment-full size-full wp-image-10127\" alt=\"Appnicorn Work - iGOZO\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo-131x300.jpg 131w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo-447x1024.jpg 447w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo-768x1758.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo-671x1536.jpg 671w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo-895x2048.jpg 895w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo-5x12.jpg 5w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_igozo-600x1373.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f0a09e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0a09e7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-08a91e9\" data-id=\"08a91e9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16243ee elementor-widget elementor-widget-heading\" data-id=\"16243ee\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pangu<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c7b34 elementor-widget elementor-widget-text-editor\" data-id=\"32c7b34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u5c06Pangu\u7684\u613f\u666f\u8f6c\u5316\u4e3a\u7535\u5b50\u5546\u52a1\u4f53\u9a8c\uff0c \u8ba9\u987e\u5ba2\u80fd\u8f7b\u677e\u5728\u7ebf\u4e0a\u70b9\u51fb\u8d2d\u4e70\u8dd1\u978b\u548c\u6237\u5916\u88c5\u5907\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93d0e3d elementor-widget elementor-widget-text-editor\" data-id=\"93d0e3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1 | \u7535\u5b50\u5546\u52a1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4f7daa elementor-widget elementor-widget-premium-image-scroll\" data-id=\"a4f7daa\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/pangu\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1244\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_pangu.jpg\" class=\"attachment-full size-full wp-image-10192\" alt=\"Pangu is Appnicorn&#039;s E-commerce web development client.\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_pangu.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_pangu-229x300.jpg 229w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_pangu-782x1024.jpg 782w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_pangu-768x1006.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_pangu-9x12.jpg 9w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_pangu-600x786.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d87d1a\" data-id=\"0d87d1a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-044b84d elementor-widget elementor-widget-heading\" data-id=\"044b84d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CST Training<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0a9e5 elementor-widget elementor-widget-text-editor\" data-id=\"1f0a9e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u901a\u8fc7CST\u57f9\u8bad\uff0c \u4f53\u9a8c\u987a\u7545\u7684\u6d3b\u52a8\u7ba1\u7406\u548c\u7968\u52a1\u670d\u52a1\u2014\u2014\u901a\u5f80\u96be\u5fd8\u4f53\u9a8c\u548c\u7f8e\u597d\u65f6\u523b\u7684\u95e8\u6237\uff01<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae133b6 elementor-widget elementor-widget-text-editor\" data-id=\"ae133b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1 | \u7535\u5b50\u7968\u52a1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beb69f3 elementor-widget elementor-widget-premium-image-scroll\" data-id=\"beb69f3\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/cst-training\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"2159\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain.jpg\" class=\"attachment-full size-full wp-image-10182\" alt=\"Appnicorn Work - CST Training\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain-132x300.jpg 132w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain-451x1024.jpg 451w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain-768x1745.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain-676x1536.jpg 676w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain-901x2048.jpg 901w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain-5x12.jpg 5w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_csttrain-600x1364.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-beee501 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"beee501\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9c75ab2\" data-id=\"9c75ab2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-904333d elementor-widget elementor-widget-heading\" data-id=\"904333d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruvine Beauty<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b3765e elementor-widget elementor-widget-text-editor\" data-id=\"7b3765e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u4e2a\u4eba\u62a4\u7406\u3001 \u62a4\u80a4\u548c\u5316\u5986\u54c1\u7684\u9996\u9009\u76ee\u7684\u5730\uff0c \u63d0\u5347\u987e\u5ba2\u7684\u81ea\u7136\u5149\u5f69\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f810dab elementor-widget elementor-widget-text-editor\" data-id=\"f810dab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7758a57 elementor-widget elementor-widget-premium-image-scroll\" data-id=\"7758a57\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/ruvine-beauty\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1587\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine.jpg\" class=\"attachment-full size-full wp-image-10147\" alt=\"Appnicorn Work - Ruvine Beauty\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine-180x300.jpg 180w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine-613x1024.jpg 613w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine-768x1283.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine-919x1536.jpg 919w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine-7x12.jpg 7w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_ruvine-600x1002.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22b29fa\" data-id=\"22b29fa\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-520fb30 elementor-widget elementor-widget-heading\" data-id=\"520fb30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vision Building<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02004e2 elementor-widget elementor-widget-text-editor\" data-id=\"02004e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u5c55\u793aVision Building\u72ec\u7279\u4f18\u52bf\u7684\u7edf\u4e00\u5728\u7ebf\u4f53\u9a8c\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33e715f elementor-widget elementor-widget-text-editor\" data-id=\"33e715f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4177710 elementor-widget elementor-widget-premium-image-scroll\" data-id=\"4177710\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/vision-building\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1600\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild.jpg\" class=\"attachment-full size-full wp-image-10222\" alt=\"Appnicorn Work - Vision Building\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild-178x300.jpg 178w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild-608x1024.jpg 608w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild-768x1293.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild-912x1536.jpg 912w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild-7x12.jpg 7w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_visionbuild-600x1011.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7715545 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7715545\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9b5b0a4\" data-id=\"9b5b0a4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80c786d elementor-widget elementor-widget-heading\" data-id=\"80c786d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lifyn<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5af940 elementor-widget elementor-widget-text-editor\" data-id=\"c5af940\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u5c06\u7269\u4e1a\u6539\u9020\u63d0\u5347\u5230\u65b0\u7684\u9ad8\u5ea6\uff0c \u521b\u9020\u4ee4\u4eba\u60ca\u53f9\u7684\u73af\u5883\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5268bec elementor-widget elementor-widget-text-editor\" data-id=\"5268bec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a83e519 elementor-widget elementor-widget-premium-image-scroll\" data-id=\"a83e519\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/lifyn\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"2415\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom.jpg\" class=\"attachment-full size-full wp-image-10193\" alt=\"Appnicorn Work - Lifyn\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom-118x300.jpg 118w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom-403x1024.jpg 403w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom-768x1952.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom-604x1536.jpg 604w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom-806x2048.jpg 806w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom-5x12.jpg 5w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_lifyncom-600x1525.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7746579\" data-id=\"7746579\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10f9bff elementor-widget elementor-widget-heading\" data-id=\"10f9bff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">The Estate<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69d676f elementor-widget elementor-widget-text-editor\" data-id=\"69d676f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u4f18\u96c5\u7684\u6d3b\u52a8\u573a\u5730\u79df\u8d41\uff0c\u65e8\u5728\u521b\u9020\u96be\u5fd8\u7684\u65f6\u523b\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50096fa elementor-widget elementor-widget-text-editor\" data-id=\"50096fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70958ec elementor-widget elementor-widget-premium-image-scroll\" data-id=\"70958ec\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/the-estate\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1446\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_estateKL.jpg\" class=\"attachment-full size-full wp-image-10226\" alt=\"Appnicorn Work - Estate KL\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_estateKL.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_estateKL-197x300.jpg 197w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_estateKL-673x1024.jpg 673w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_estateKL-768x1169.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_estateKL-8x12.jpg 8w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_estateKL-600x913.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-97ccc4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97ccc4d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-505d82b\" data-id=\"505d82b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea3672e elementor-widget elementor-widget-heading\" data-id=\"ea3672e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">EM Loan<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-842a39c elementor-widget elementor-widget-text-editor\" data-id=\"842a39c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u4e3aEM Loan\u63d0\u4f9b\u7528\u6237\u53cb\u597d\u7684\u7535\u5b50\u8d37\u6b3e\u5e94\u7528\u7a0b\u5e8f\u548c\u7f51\u7ad9\uff0c \u7b80\u5316\u501f\u8d37\u6d41\u7a0b\uff0c \u63d0\u5347\u91d1\u878d\u53ef\u53ca\u6027\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1187e6e elementor-widget elementor-widget-text-editor\" data-id=\"1187e6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u79fb\u52a8\u5e94\u7528\u7a0b\u5e8f\u5f00\u53d1 | \u7f51\u9875\u5f00\u53d1 | \u6570\u5b57\u501f\u8d37<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a3ee6a elementor-widget elementor-widget-premium-image-scroll\" data-id=\"6a3ee6a\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/em-loan\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1899\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_emloan.jpg\" class=\"attachment-full size-full wp-image-10218\" alt=\"EM Loan is Appnicorn&#039;s E-lending mobile app development client.\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_emloan.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_emloan-150x300.jpg 150w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_emloan-512x1024.jpg 512w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_emloan-768x1536.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_emloan-6x12.jpg 6w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_emloan-600x1199.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb85dad\" data-id=\"cb85dad\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fc1da2 elementor-widget elementor-widget-heading\" data-id=\"3fc1da2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">JiranKu<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8122a51 elementor-widget elementor-widget-text-editor\" data-id=\"8122a51\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u4e00\u4e2a\u5373\u5c06\u63a8\u51fa\u7684\u4f4f\u5b85\u793e\u533a\u5e73\u53f0\uff0c \u8fde\u63a5\u793e\u533a\u5c45\u6c11\u5e76\u63d0\u5347\u793e\u533a\u751f\u6d3b\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ee8e54 elementor-widget elementor-widget-text-editor\" data-id=\"2ee8e54\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u79fb\u52a8\u5e94\u7528\u7a0b\u5e8f\u5f00\u53d1 | \u7f51\u9875\u5f00\u53d1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26f794f elementor-widget elementor-widget-premium-image-scroll\" data-id=\"26f794f\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/jiranku\/\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1641\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku.jpg\" class=\"attachment-full size-full wp-image-10214\" alt=\"JiranKu is Appnicorn&#039;s mobile app development client.\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku-174x300.jpg 174w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku-593x1024.jpg 593w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku-768x1327.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku-889x1536.jpg 889w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku-7x12.jpg 7w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_jiranku-600x1036.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-70cfa00 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70cfa00\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29d4675\" data-id=\"29d4675\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3007c6 elementor-widget elementor-widget-heading\" data-id=\"b3007c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3cat<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54a8faa elementor-widget elementor-widget-text-editor\" data-id=\"54a8faa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>3cat \u662f\u9a6c\u6765\u897f\u4e9a\u4e00\u4e2a\u503c\u5f97\u4fe1\u8d56\u7684\u5e73\u53f0\uff0c\u4e13\u95e8\u7528\u4e8e\u8d2d\u4e70\u3001\u4ea4\u6613\u548c\u7ef4\u4fee\u4e8c\u624b Apple \u8bbe\u5907\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db7c799 elementor-widget elementor-widget-text-editor\" data-id=\"db7c799\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>IT Support<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db93fa2 elementor-widget elementor-widget-premium-image-scroll\" data-id=\"db93fa2\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"652\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-3cat-web.jpg\" class=\"attachment-full size-full wp-image-12002\" alt=\"\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-3cat-web.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-3cat-web-300x206.jpg 300w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-3cat-web-768x527.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-3cat-web-18x12.jpg 18w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-3cat-web-600x412.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a9ff22e\" data-id=\"a9ff22e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25e93ed elementor-widget elementor-widget-heading\" data-id=\"25e93ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Coros Malaysia<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6726b2 elementor-widget elementor-widget-text-editor\" data-id=\"f6726b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u4e3a\u8fd0\u52a8\u5458\u8bbe\u8ba1\u7684\u521b\u65b0\u53ef\u7a7f\u6234\u8bbe\u5907\uff0c\u63d0\u4f9b\u5148\u8fdb\u7684\u6027\u80fd\u8ffd\u8e2a\u548c GPS \u6280\u672f\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6276418 elementor-widget elementor-widget-text-editor\" data-id=\"6276418\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u7f51\u9875\u5f00\u53d1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccee1e7 elementor-widget elementor-widget-premium-image-scroll\" data-id=\"ccee1e7\" data-element_type=\"widget\" data-widget_type=\"premium-image-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"premium-image-scroll-section\" >\r\n\t\t\t\t<div class=\"premium-image-scroll-container\" data-settings=\"{&quot;trigger&quot;:&quot;hover&quot;,&quot;direction&quot;:&quot;vertical&quot;,&quot;reverse&quot;:&quot;&quot;}\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-image-scroll-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-scroll-link\" href=\"https:\/\/www.coros.my\/\" target=\"_blank\"><\/a>\r\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1926\" src=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia.jpg\" class=\"attachment-full size-full wp-image-12009\" alt=\"Coros Malaysia\" srcset=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia.jpg 950w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia-148x300.jpg 148w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia-505x1024.jpg 505w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia-768x1557.jpg 768w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia-758x1536.jpg 758w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia-6x12.jpg 6w, https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/12\/portfolio-coros-malaysia-600x1216.jpg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62ee846 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62ee846\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1cd020f\" data-id=\"1cd020f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7aacfa0 elementor-widget elementor-widget-heading\" data-id=\"7aacfa0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u4e00\u8d77\u4ea4\u6d41\u5427\u3002<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e21a9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e21a9f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5ecb4f6\" data-id=\"5ecb4f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c21bb4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8c21bb4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/appnicorn.com\/zh\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u8054\u7cfb\u6211\u4eec<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>OUR WORK Designing impactful online presences for brands. Appnicorn is a dynamic web design agency, proficient in turning your brand vision into reality through exceptional web design, strategic SEO, e-commerce solutions, and app development. Simble Sleek and user-friendly WordPress websites with seamless e-commerce support. Web Development | E-Commerce iGOZO One-stop online shop for high-quality cookware&hellip;&nbsp;<a href=\"https:\/\/appnicorn.com\/zh\/our-work\/\" class=\"\" rel=\"bookmark\">\u9605\u8bfb\u66f4\u591a &raquo;<span class=\"screen-reader-text\">\u5ba2\u6237\u6848\u4f8b<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"class_list":["post-10055","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v20.13) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Our Work | Web Design Portfolio | E-commerce &amp; SEO Projects<\/title>\n<meta name=\"description\" content=\"Explore our portfolio showcasing web design, e-commerce &amp; SEO projects. Discover how our creative solutions can drive your online success!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/appnicorn.com\/zh\/our-work\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our Work | Web Design Portfolio | E-commerce &amp; SEO Projects\" \/>\n<meta property=\"og:description\" content=\"Explore our portfolio showcasing web design, e-commerce &amp; SEO projects. Discover how our creative solutions can drive your online success!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/appnicorn.com\/zh\/our-work\/\" \/>\n<meta property=\"og:site_name\" content=\"Appnicorn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/appnicorn\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T09:14:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/appnicorn.com\/our-work\/\",\"url\":\"https:\/\/appnicorn.com\/our-work\/\",\"name\":\"Our Work | Web Design Portfolio | E-commerce & SEO Projects\",\"isPartOf\":{\"@id\":\"https:\/\/appnicorn.com\/#website\"},\"datePublished\":\"2024-09-27T07:05:57+00:00\",\"dateModified\":\"2025-02-17T09:14:31+00:00\",\"description\":\"Explore our portfolio showcasing web design, e-commerce & SEO projects. Discover how our creative solutions can drive your online success!\",\"breadcrumb\":{\"@id\":\"https:\/\/appnicorn.com\/our-work\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/appnicorn.com\/our-work\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/appnicorn.com\/our-work\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/appnicorn.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Work\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/appnicorn.com\/#website\",\"url\":\"https:\/\/appnicorn.com\/\",\"name\":\"Appnicorn Sdn Bhd\",\"description\":\"Web Design &amp; Mobile App Development Malaysia\",\"publisher\":{\"@id\":\"https:\/\/appnicorn.com\/#organization\"},\"alternateName\":\"Appnicorn Web Design & Mobile App Development\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/appnicorn.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/appnicorn.com\/#organization\",\"name\":\"Appnicorn Sdn Bhd\",\"alternateName\":\"Appnicorn\",\"url\":\"https:\/\/appnicorn.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/appnicorn.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/appnicorn-com.s3.ap-southeast-1.amazonaws.com\/wp-content\/uploads\/2023\/08\/03132332\/Appnicorn_CompanyLogo.png\",\"contentUrl\":\"https:\/\/appnicorn-com.s3.ap-southeast-1.amazonaws.com\/wp-content\/uploads\/2023\/08\/03132332\/Appnicorn_CompanyLogo.png\",\"width\":3001,\"height\":751,\"caption\":\"Appnicorn Sdn Bhd\"},\"image\":{\"@id\":\"https:\/\/appnicorn.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/appnicorn\/\",\"https:\/\/www.linkedin.com\/company\/appnicorn\/\",\"https:\/\/www.instagram.com\/appnicorn\/\",\"https:\/\/www.youtube.com\/@appnicorn\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Our Work | Web Design Portfolio | E-commerce & SEO Projects","description":"Explore our portfolio showcasing web design, e-commerce & SEO projects. Discover how our creative solutions can drive your online success!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/appnicorn.com\/zh\/our-work\/","og_locale":"zh_CN","og_type":"article","og_title":"Our Work | Web Design Portfolio | E-commerce & SEO Projects","og_description":"Explore our portfolio showcasing web design, e-commerce & SEO projects. Discover how our creative solutions can drive your online success!","og_url":"https:\/\/appnicorn.com\/zh\/our-work\/","og_site_name":"Appnicorn","article_publisher":"https:\/\/www.facebook.com\/appnicorn\/","article_modified_time":"2025-02-17T09:14:31+00:00","og_image":[{"url":"https:\/\/appnicorn.com\/wp-content\/uploads\/2024\/09\/appnicorn_our_work_simblelife.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"4 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/appnicorn.com\/our-work\/","url":"https:\/\/appnicorn.com\/our-work\/","name":"Our Work | Web Design Portfolio | E-commerce & SEO Projects","isPartOf":{"@id":"https:\/\/appnicorn.com\/#website"},"datePublished":"2024-09-27T07:05:57+00:00","dateModified":"2025-02-17T09:14:31+00:00","description":"Explore our portfolio showcasing web design, e-commerce & SEO projects. Discover how our creative solutions can drive your online success!","breadcrumb":{"@id":"https:\/\/appnicorn.com\/our-work\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/appnicorn.com\/our-work\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/appnicorn.com\/our-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/appnicorn.com\/"},{"@type":"ListItem","position":2,"name":"Our Work"}]},{"@type":"WebSite","@id":"https:\/\/appnicorn.com\/#website","url":"https:\/\/appnicorn.com\/","name":"Appnicorn Sdn Bhd","description":"Web Design &amp; Mobile App Development Malaysia","publisher":{"@id":"https:\/\/appnicorn.com\/#organization"},"alternateName":"Appnicorn Web Design & Mobile App Development","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/appnicorn.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/appnicorn.com\/#organization","name":"Appnicorn Sdn Bhd","alternateName":"Appnicorn","url":"https:\/\/appnicorn.com\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/appnicorn.com\/#\/schema\/logo\/image\/","url":"https:\/\/appnicorn-com.s3.ap-southeast-1.amazonaws.com\/wp-content\/uploads\/2023\/08\/03132332\/Appnicorn_CompanyLogo.png","contentUrl":"https:\/\/appnicorn-com.s3.ap-southeast-1.amazonaws.com\/wp-content\/uploads\/2023\/08\/03132332\/Appnicorn_CompanyLogo.png","width":3001,"height":751,"caption":"Appnicorn Sdn Bhd"},"image":{"@id":"https:\/\/appnicorn.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/appnicorn\/","https:\/\/www.linkedin.com\/company\/appnicorn\/","https:\/\/www.instagram.com\/appnicorn\/","https:\/\/www.youtube.com\/@appnicorn"]}]}},"_links":{"self":[{"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/pages\/10055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/comments?post=10055"}],"version-history":[{"count":3,"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/pages\/10055\/revisions"}],"predecessor-version":[{"id":12510,"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/pages\/10055\/revisions\/12510"}],"wp:attachment":[{"href":"https:\/\/appnicorn.com\/zh\/wp-json\/wp\/v2\/media?parent=10055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}